{"id":6818,"date":"2023-08-23T13:30:02","date_gmt":"2023-08-23T13:30:02","guid":{"rendered":"https:\/\/botiga.saiga.es\/producte\/debroussailleuse-echo-srm-2621tes-u\/"},"modified":"2026-05-12T10:58:40","modified_gmt":"2026-05-12T10:58:40","slug":"debroussailleuse-echo-srm-2621tes-u","status":"publish","type":"product","link":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/","title":{"rendered":"D\u00e9broussailleuse Echo SRM 2621TES U"},"content":{"rendered":"<p>D\u00e9broussailleuse \u00e0 couple \u00e9lev\u00e9 ECHO SRM 2621 T ESU avec r\u00e9ducteur, double guidon, l\u00e9g\u00e8re et puissante, d\u00e9marrage facile ES-Start, allumage \u00e9lectronique CDI, EUST5.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9broussailleuse \u00e0 couple \u00e9lev\u00e9 ECHO SRM 2621 T ESU avec r\u00e9ducteur, double guidon, l\u00e9g\u00e8re et puissante, d\u00e9marrage facile ES-Start, allumage \u00e9lectronique CDI, EUST5.<\/p>\n","protected":false},"featured_media":6819,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1698],"product_tag":[1795,514,1667],"class_list":{"0":"post-6818","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-debroussailleuse","7":"product_tag-debroussailleuse","8":"product_tag-desherbage","9":"product_tag-echo-fr","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA\" \/>\n<meta property=\"og:description\" content=\"D\u00e9broussailleuse \u00e0 couple \u00e9lev\u00e9 ECHO SRM 2621 T ESU avec r\u00e9ducteur, double guidon, l\u00e9g\u00e8re et puissante, d\u00e9marrage facile ES-Start, allumage \u00e9lectronique CDI, EUST5.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/\" \/>\n<meta property=\"og:site_name\" content=\"SAIGA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saiga.es\/wp-content\/uploads\/2023\/08\/desbrozadora-srm-2621-t-esu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@saiga_agro\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/\",\"url\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/\",\"name\":\"D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saiga.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/desbrozadora-srm-2621-t-esu.png\",\"datePublished\":\"2023-08-23T13:30:02+00:00\",\"dateModified\":\"2026-05-12T10:58:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saiga.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/desbrozadora-srm-2621-t-esu.png\",\"contentUrl\":\"https:\\\/\\\/saiga.es\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/desbrozadora-srm-2621-t-esu.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/produit\\\/debroussailleuse-echo-srm-2621tes-u\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/saiga.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"boutique\",\"item\":\"https:\\\/\\\/saiga.es\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9broussailleuse Echo SRM 2621TES U\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/saiga.es\\\/fr\\\/\",\"name\":\"SAIGA\",\"description\":\"M\u00e9s de 50 anys al servei de la terra i treballant per a un \u00fas eficient de l\u2019aigua!\",\"publisher\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saiga.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#organization\",\"name\":\"SAIGA\",\"url\":\"https:\\\/\\\/saiga.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/saiga.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo_saiga_baseline_optimitzat.svg\",\"contentUrl\":\"https:\\\/\\\/saiga.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo_saiga_baseline_optimitzat.svg\",\"caption\":\"SAIGA\"},\"image\":{\"@id\":\"https:\\\/\\\/saiga.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/saiga_agro\",\"https:\\\/\\\/www.instagram.com\\\/saiga_agro\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA","og_description":"D\u00e9broussailleuse \u00e0 couple \u00e9lev\u00e9 ECHO SRM 2621 T ESU avec r\u00e9ducteur, double guidon, l\u00e9g\u00e8re et puissante, d\u00e9marrage facile ES-Start, allumage \u00e9lectronique CDI, EUST5.","og_url":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/","og_site_name":"SAIGA","article_modified_time":"2026-05-12T10:58:40+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/saiga.es\/wp-content\/uploads\/2023\/08\/desbrozadora-srm-2621-t-esu.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@saiga_agro","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/","url":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/","name":"D\u00e9broussailleuse Echo SRM 2621TES U | SAIGA","isPartOf":{"@id":"https:\/\/saiga.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/#primaryimage"},"image":{"@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/#primaryimage"},"thumbnailUrl":"https:\/\/saiga.es\/wp-content\/uploads\/2023\/08\/desbrozadora-srm-2621-t-esu.png","datePublished":"2023-08-23T13:30:02+00:00","dateModified":"2026-05-12T10:58:40+00:00","breadcrumb":{"@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/#primaryimage","url":"https:\/\/saiga.es\/wp-content\/uploads\/2023\/08\/desbrozadora-srm-2621-t-esu.png","contentUrl":"https:\/\/saiga.es\/wp-content\/uploads\/2023\/08\/desbrozadora-srm-2621-t-esu.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/saiga.es\/fr\/produit\/debroussailleuse-echo-srm-2621tes-u\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/saiga.es\/fr\/"},{"@type":"ListItem","position":2,"name":"boutique","item":"https:\/\/saiga.es\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"D\u00e9broussailleuse Echo SRM 2621TES U"}]},{"@type":"WebSite","@id":"https:\/\/saiga.es\/fr\/#website","url":"https:\/\/saiga.es\/fr\/","name":"SAIGA","description":"M\u00e9s de 50 anys al servei de la terra i treballant per a un \u00fas eficient de l\u2019aigua!","publisher":{"@id":"https:\/\/saiga.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saiga.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/saiga.es\/fr\/#organization","name":"SAIGA","url":"https:\/\/saiga.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/saiga.es\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/saiga.es\/wp-content\/uploads\/2025\/07\/logo_saiga_baseline_optimitzat.svg","contentUrl":"https:\/\/saiga.es\/wp-content\/uploads\/2025\/07\/logo_saiga_baseline_optimitzat.svg","caption":"SAIGA"},"image":{"@id":"https:\/\/saiga.es\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/saiga_agro","https:\/\/www.instagram.com\/saiga_agro\/"]}]}},"_links":{"self":[{"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/product\/6818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/comments?post=6818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/media\/6819"}],"wp:attachment":[{"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/media?parent=6818"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/product_brand?post=6818"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/product_cat?post=6818"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saiga.es\/fr\/wp-json\/wp\/v2\/product_tag?post=6818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}